{"id":13042,"date":"2026-03-24T09:41:38","date_gmt":"2026-03-24T09:41:38","guid":{"rendered":"https:\/\/glabridinchina.com\/?post_type=product&#038;p=13042"},"modified":"2026-07-30T08:24:05","modified_gmt":"2026-07-30T08:24:05","slug":"liquiritigenin","status":"publish","type":"product","link":"https:\/\/glabridinchina.com\/it\/prodotto\/liquiritigenin\/","title":{"rendered":"Liquiritigenina"},"content":{"rendered":"<h2 data-path-to-node=\"0\">L'Ultimo Liquiritigenina 100% Senza Farnesolo: Ingegnerizzata su Misura per Pelli Estremamente Sensibili e Zero Sensibilizzazione<\/h2>\n<p data-path-to-node=\"1\"><b data-path-to-node=\"1\" data-index-in-node=\"0\">Clinicamente provato per ridurre il pizzicore percepito e l'irritazione neurogena del 60% in soli 3 minuti, disattivando istantaneamente rossore e disagio visibili.<\/b><\/p>\n<p data-path-to-node=\"2\">Nel settore avanzato della cura della pelle dermatologica, fornire un sollievo istantaneo senza scatenare ulteriore irritazione \u00e8 la sfida formulativa definitiva. La nostra Liquiritigenina di Grado Cosmetico premium \u00e8 rigorosamente ingegnerizzata per rimuovere completamente le impurit\u00e0. Costruita per essere 100% priva di farnesolo, stabilisce un profilo di sicurezza impeccabile che elimina il rischio di sensibilizzazione indotta da ingredienti. Modulando selettivamente i recettori TRPV1 (i sensori di calore e dolore della pelle), questo flavonoide aglicone ad alta purezza arresta la cascata infiammatoria, neutralizza i radicali liberi e fornisce un comfort sensoriale immediato alla pelle iperreattiva.<\/p>\n<h3 data-path-to-node=\"4\">Sbloccare un Valore Aziendale Ineguagliabile.<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13047 alignright\" src=\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin-225x300.jpg\" alt=\"\" width=\"276\" height=\"368\" srcset=\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin-225x300.jpg 225w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin-768x1024.jpg 768w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin-9x12.jpg 9w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin-600x800.jpg 600w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin-1x1.jpg 1w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin-8x10.jpg 8w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Cosmetic-Grade-Liquiritigenin.jpg 1134w\" sizes=\"auto, (max-width: 276px) 100vw, 276px\" \/><\/p>\n<p data-path-to-node=\"5\"><b data-path-to-node=\"5\" data-index-in-node=\"0\">Per Innovatori OEM\/ODM Globali:<\/b> Ottenere un'eleganza formulativa definitiva e un'estrema compatibilit\u00e0. A differenza degli estratti grezzi e scuri di liquirizia, la nostra Liquiritigenina altamente purificata si integra perfettamente senza scurire significativamente il prodotto finale. Offre un profilo raffinato e completamente inodore e una limpidezza bianco acqua se formulata correttamente, garantendo che non comprometter\u00e0 mai il colore preciso, la fragranza o l'estetica della vostra emulsione finale. Eccezionalmente stabile all'aria e alla luce, elimina completamente l'attrito di produzione per i vostri team di ricerca e sviluppo.<\/p>\n<p data-path-to-node=\"6\"><b data-path-to-node=\"6\" data-index-in-node=\"0\">Per Marchi di Bellezza di Alta Gamma:<\/b> Elevare il posizionamento di mercato e le dichiarazioni cliniche. Questo attivo ultra-puro \u00e8 la scelta distintiva per i rigorosi mandati \"Clean Beauty\" e per le formulazioni altamente tollerabili \"SOS Emergency Repair\". Permetti al tuo marchio di commercializzare miracoli lenitivi \"di primo soccorso\" e \"anti-pizzicore\". Cattura la feroce lealt\u00e0 dei consumatori che richiedono cure neuro-calmanti altamente potenti e non sensibilizzanti che offrono una riduzione visibile del rossore e un'attenuazione sensoriale entro pochi minuti dall'applicazione.<\/p>\n<h3 data-path-to-node=\"8\">Panoramica del Prodotto e Specifiche Chiave<\/h3>\n<ul data-path-to-node=\"9\">\n<li>\n<p data-path-to-node=\"9,0,0\"><b data-path-to-node=\"9,0,0\" data-index-in-node=\"0\">Aspetto:<\/b> Polvere raffinata ad alta purezza (adatta a formulazioni trasparenti; evita l'imbrunimento degli estratti grezzi)<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,1,0\"><b data-path-to-node=\"9,1,0\" data-index-in-node=\"0\">Odore:<\/b> Inodore (neutro alla fragranza)<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,2,0\"><b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">Purezza:<\/b> \u2265 98.0% (Nessun acido glicirrizico residuo)<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,3,0\"><b data-path-to-node=\"9,3,0\" data-index-in-node=\"0\">Metalli pesanti:<\/b> &lt; 10 ppm<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,4,0\"><b data-path-to-node=\"9,4,0\" data-index-in-node=\"0\">Utilizzo consigliato:<\/b> 05% \u2013 0.2% (Skincare Standard) \/ Fino a 0.5% (Sieri Intensivi SOS Rescue)<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,5,0\"><b data-path-to-node=\"9,5,0\" data-index-in-node=\"0\">Stabilit\u00e0 del Range di pH:<\/b> Eccezionalmente stabile tra 4.0 e 7.0<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,6,0\"><b data-path-to-node=\"9,6,0\" data-index-in-node=\"0\">Linee Guida di Lavorazione:<\/b> Pre-sciogliere in un poliolo (come il Propanediolo) o aggiungere direttamente alla fase oleosa prima dell'emulsificazione.<\/p>\n<\/li>\n<\/ul>\n<h3 data-path-to-node=\"11\">Soluzioni Pronte all'Uso: Le Sinergie d'Oro<\/h3>\n<p data-path-to-node=\"12\">Fornisci al tuo laboratorio di ricerca e sviluppo un progetto immediato per il successo sul mercato. La nostra Liquiritigenina agisce come un supremo neuro-calmante biologico, proteggendo e amplificando l'efficacia riparatrice degli attivi complementari:<\/p>\n<ul data-path-to-node=\"13\">\n<li>\n<p data-path-to-node=\"13,0,0\"><b data-path-to-node=\"13,0,0\" data-index-in-node=\"0\">Liquiritigenina + Allantoina:<\/b> La matrice definitiva per il sollievo dal pizzicore e la guarigione delle ferite. Combina la rapida inibizione neurogena TRPV1 della Liquiritigenina con la rigenerazione cellulare idrosolubile dell'Allantoina per eliminare istantaneamente i micro-traumi e lenire in sicurezza la pelle post-procedura.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"13,1,0\"><b data-path-to-node=\"13,1,0\" data-index-in-node=\"0\">Liquiritigenina + Pantenolo:<\/b> Un sistema completo \"SOS Barrier Rescue\". Il Pantenolo inonda lo strato corneo con un'idratazione profonda e mirata, creando un ambiente sano e non reattivo che consente alla Liquiritigenina di \"spegnere\" efficacemente il rossore visibile e la vasodilatazione infiammatoria senza scatenare irritazioni.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"13,2,0\"><b data-path-to-node=\"13,2,0\" data-index-in-node=\"0\">Liquiritigenina + Ceramide NP:<\/b> Il complesso assoluto di difesa strutturale e sensoriale. Mentre la Liquiritigenina attenua istantaneamente la reattivit\u00e0 cutanea acuta e lo stress ambientale dall'interno, la Ceramide NP ricostruisce in sicurezza e fisicamente il cemento lipidico impoverito della pelle in superficie, garantendo una barriera cutanea resiliente, calma e perfettamente protetta.<\/p>\n<\/li>\n<\/ul>\n<h3 data-path-to-node=\"15\">Garanzia di Qualit\u00e0 Senza Compromessi<\/h3>\n<p data-path-to-node=\"16\">Formula con assoluta sicurezza normativa. Shaanxi Huatai Bio-Fine Chemicals Co. aderisce rigorosamente ai parametri di riferimento globali per la sicurezza cosmetica, garantendo che i nostri derivati botanici superino le valutazioni tossicologiche pi\u00f9 rigorose. Il nostro impianto di produzione all'avanguardia opera secondo i pi\u00f9 alti standard globali, pienamente certificato da:<\/p>\n<ul data-path-to-node=\"17\">\n<li>\n<p data-path-to-node=\"17,0,0\"><b data-path-to-node=\"17,0,0\" data-index-in-node=\"0\">ISO<\/b><\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"17,1,0\"><b data-path-to-node=\"17,1,0\" data-index-in-node=\"0\">COSMO<\/b><\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"17,2,0\"><b data-path-to-node=\"17,2,0\" data-index-in-node=\"0\">HALAL<\/b><\/p>\n<\/li>\n<\/ul>\n<p data-path-to-node=\"18\"><i data-path-to-node=\"18\" data-index-in-node=\"0\">Ogni lotto \u00e8 supportato da un dossier tecnico completo per semplificare i vostri processi di conformit\u00e0 globale, trasparenza della catena di approvvigionamento e archiviazione normativa.<\/i><\/p>\n<h3 data-path-to-node=\"0\">Domande frequenti (FAQ)<\/h3>\n<table data-path-to-node=\"1\">\n<thead>\n<tr>\n<td><strong>Domanda<\/strong><\/td>\n<td><strong>Risposta<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><span data-path-to-node=\"1,1,0,0\"><b data-path-to-node=\"1,1,0,0\" data-index-in-node=\"0\">Cos'\u00e8 la Liquiritigenina e il tuo estratto \u00e8 di origine naturale?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,1,1,0\">La Liquiritigenina \u00e8 un flavonoide altamente attivo presente in natura nelle radici di liquirizia. <b data-path-to-node=\"1,1,1,0\" data-index-in-node=\"79\">Shaanxi Huatai<\/b> utilizza tecnologie di estrazione avanzate per fornire Liquiritigenina naturale al 100%, garantendo la massima attivit\u00e0 biologica per cosmetici premium schiarenti e anti-invecchiamento.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"1,2,0,0\"><b data-path-to-node=\"1,2,0,0\" data-index-in-node=\"0\">Come funziona la Liquiritigenina per lo sbiancamento della pelle e quali sono i suoi principali benefici?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,2,1,0\">Agisce come un potente inibitore della tirosinasi, riducendo efficacemente la produzione di melanina e offrendo forti propriet\u00e0 antiossidanti. I formulatori cosmetici globali scelgono la Liquiritigenina premium da <b data-path-to-node=\"1,2,1,0\" data-index-in-node=\"196\">Shaanxi Huatai<\/b> per sviluppare correttori di macchie scure e sieri lenitivi altamente efficaci.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"1,3,0,0\"><b data-path-to-node=\"1,3,0,0\" data-index-in-node=\"0\">La tua Liquiritigenina di grado cosmetico \u00e8 solubile in acqua o in olio?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,3,1,0\">La Liquiritigenina \u00e8 altamente solubile in glicoli e alcoli cosmetici (come glicole propilenico o glicole butilenico) piuttosto che in acqua pura. Il team di ricerca e sviluppo di <b data-path-to-node=\"1,3,1,0\" data-index-in-node=\"173\">Shaanxi Huatai<\/b> fornisce linee guida dettagliate sulla formulazione per aiutarti a incorporarla facilmente nei tuoi sistemi di emulsione.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"1,4,0,0\"><b data-path-to-node=\"1,4,0,0\" data-index-in-node=\"0\">Qual \u00e8 il tasso di utilizzo raccomandato per la Liquiritigenina nelle formulazioni per la cura della pelle?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,4,1,0\">Per risultati ottimali di schiarimento della pelle e anti-infiammatori, il tasso di utilizzo raccomandato varia tipicamente dallo 0,05% allo 0,5% a seconda del tipo di prodotto finale. Gli esperti tecnici di <b data-path-to-node=\"1,4,1,0\" data-index-in-node=\"191\">Shaanxi Huatai<\/b> sono sempre disponibili per aiutare a ottimizzare il dosaggio per le tue formule specifiche.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"1,5,0,0\"><b data-path-to-node=\"1,5,0,0\" data-index-in-node=\"0\">L'uso della Liquiritigenina causer\u00e0 irritazione o cambier\u00e0 il colore del mio prodotto finale?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,5,1,0\">La Liquiritigenina \u00e8 nota per le sue eccellenti propriet\u00e0 lenitive ed \u00e8 altamente adatta per pelli sensibili. Inoltre, <b data-path-to-node=\"1,5,1,0\" data-index-in-node=\"118\">Shaanxi Huatai<\/b> utilizza metodi di purificazione avanzati per garantire che l'estratto sia altamente raffinato, riducendo al minimo qualsiasi impatto sul colore delle tue creme o sieri bianchi premium.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"1,6,0,0\"><b data-path-to-node=\"1,6,0,0\" data-index-in-node=\"0\">Fornite il Certificato di Analisi (COA) e la MSDS per ordini all'ingrosso?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,6,1,0\">Il rigoroso controllo di qualit\u00e0 \u00e8 lo standard presso il nostro impianto di produzione. <b data-path-to-node=\"1,6,1,0\" data-index-in-node=\"70\">Shaanxi Huatai<\/b> fornisce documentazione completa e specifica per lotto per ogni spedizione all'ingrosso, inclusi il Certificato di Analisi (COA), la Scheda di Dati di Sicurezza dei Materiali (MSDS) e i rapporti di test di purezza HPLC.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"1,7,0,0\"><b data-path-to-node=\"1,7,0,0\" data-index-in-node=\"0\">Qual \u00e8 la Quantit\u00e0 Minima d'Ordine (MOQ) e sono disponibili campioni di prova?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,7,1,0\">Per supportare laboratori di formulazione cosmetica e impianti di produzione commerciale, <b data-path-to-node=\"1,7,1,0\" data-index-in-node=\"78\">Shaanxi Huatai<\/b> offre un MOQ altamente accessibile a partire da soli 1 kg. Forniamo anche volentieri campioni di prova gratuiti da 10 g a 50 g in modo che il tuo team possa valutare la compatibilit\u00e0 della formulazione prima di ordinare all'ingrosso.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"1,8,0,0\"><b data-path-to-node=\"1,8,0,0\" data-index-in-node=\"0\">Perch\u00e9 dovrei acquistare Liquiritigenina sfusa direttamente dalla tua fabbrica in Cina?<\/b><\/span><\/td>\n<td><span data-path-to-node=\"1,8,1,0\">L'acquisto diretto da un produttore primario di estrazione di liquirizia come <b data-path-to-node=\"1,8,1,0\" data-index-in-node=\"71\">Shaanxi Huatai<\/b> garantisce che riceverai prezzi diretti di fabbrica altamente competitivi senza ricarichi di intermediari. Garantiamo un rigoroso controllo di qualit\u00e0 lotto per lotto, supporto tecnico esperto e spedizioni globali rapide.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3 data-path-to-node=\"20\">Aggiorna Oggi il Tuo Prossimo Best Seller<\/h3>\n<p data-path-to-node=\"21\">Smetti di compromettere la stabilit\u00e0 della formula, lo scolorimento degli estratti grezzi e la purezza degli ingredienti. Proteggi i tuoi consumatori ed eleva le tue linee di prodotto con lo standard globale di attivi neuro-lenitivi altamente stabili e non sensibilizzanti.<\/p>\n<p data-path-to-node=\"22\"><b data-path-to-node=\"22\" data-index-in-node=\"0\">Richiedi ora il tuo campione ad alta purezza e inodore e migliora la tua prossima formula blockbuster di riparazione!<\/b> Contact our technical sales team immediately to secure your free lab sample, request a customized bulk quote, and access the full Technical Dossier (TDS, MSDS, COA, and Clinical Efficacy Reports).<\/p>","protected":false},"excerpt":{"rendered":"<p data-path-to-node=\"11\"><b data-path-to-node=\"11\" data-index-in-node=\"0\">Lo specialista ultra-rapido per il sollievo neurologico da bruciore e arrossamento<\/b><\/p>\n<p data-path-to-node=\"12\">La liquiritigenina \u00e8 un aglicone flavonoide ad elevata purezza derivato dalla liquirizia (<i data-path-to-node=\"12\" data-index-in-node=\"74\">Glycyrrhiza glabra<\/i>Si tratta di un principio attivo cosmetico di alta qualit\u00e0, specificamente formulato per contrastare l&#039;infiammazione neurogena, ovvero la sensazione immediata di bruciore e pizzicore spesso avvertita dalla pelle sensibile. Agendo sulla risposta nervosa sensoriale, fornisce un effetto lenitivo rapidissimo e riduce visibilmente il rossore transitorio.<\/p>","protected":false},"featured_media":13048,"template":"","meta":[],"etheme_brands":[],"product_cat":[30],"product_tag":[],"class_list":{"0":"post-13042","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anti-inflammatory-soothing","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.8 (Yoast SEO v24.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liquiritigenin Powder Manufacturer &amp; Suppliers - Huatai Bio<\/title>\n<meta name=\"description\" content=\"Cosmetic Grade Liquiritigenin from a premier active ingredients skincare manufacturer. Shaanxi Huatai Bio-fine Chemical offers ISO\/HALAL\/COSMOS certified Liquiritigenin for high-end formulations. Secure wholesale pricing and request free samples from a trusted global supplier today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glabridinchina.com\/it\/prodotto\/liquiritigenin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liquiritigenin Extract | Professional Liquiritigenin Manufacturer &amp; Suppliers - Huatai Bio\" \/>\n<meta property=\"og:description\" content=\"Buy certified Liquiritigenin extracts from active skincare ingredients manufacturer. Huatai Bio supplies COSMOS\/ISO\/HALAL certified Liquiritigenin for skincare formulations. Order in bulk at competitive prices and empower your cosmetics with our reliable functional skincare ingredients. Request samples and supplier quotes now.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glabridinchina.com\/it\/prodotto\/liquiritigenin\/\" \/>\n<meta property=\"og:site_name\" content=\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-30T08:24:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/\",\"url\":\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/\",\"name\":\"Liquiritigenin Powder Manufacturer & Suppliers - Huatai Bio\",\"isPartOf\":{\"@id\":\"https:\/\/glabridinchina.com\/ru\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg\",\"datePublished\":\"2026-03-24T09:41:38+00:00\",\"dateModified\":\"2026-07-30T08:24:05+00:00\",\"description\":\"Cosmetic Grade Liquiritigenin from a premier active ingredients skincare manufacturer. Shaanxi Huatai Bio-fine Chemical offers ISO\/HALAL\/COSMOS certified Liquiritigenin for high-end formulations. Secure wholesale pricing and request free samples from a trusted global supplier today.\",\"breadcrumb\":{\"@id\":\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#primaryimage\",\"url\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg\",\"contentUrl\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg\",\"width\":800,\"height\":800,\"caption\":\"Liquiritigenin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/glabridinchina.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/glabridinchina.com\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Liquiritigenin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#website\",\"url\":\"https:\/\/glabridinchina.com\/ru\/\",\"name\":\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\",\"description\":\"Huatai Bio-Fine Chemicals: ISO-certified manufacturer of high-purity skincare ingredients like Glabridin and Tranexamic Acid. Offering flexible supply with full documentation for brands &amp; OEMs worldwide.\",\"publisher\":{\"@id\":\"https:\/\/glabridinchina.com\/ru\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/glabridinchina.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#organization\",\"name\":\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\",\"url\":\"https:\/\/glabridinchina.com\/ru\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp\",\"contentUrl\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp\",\"width\":1278,\"height\":783,\"caption\":\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\"},\"image\":{\"@id\":\"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Liquiritigenin Powder Manufacturer & Suppliers - Huatai Bio","description":"Cosmetic Grade Liquiritigenin from a premier active ingredients skincare manufacturer. Shaanxi Huatai Bio-fine Chemical offers ISO\/HALAL\/COSMOS certified Liquiritigenin for high-end formulations. Secure wholesale pricing and request free samples from a trusted global supplier today.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glabridinchina.com\/it\/prodotto\/liquiritigenin\/","og_locale":"it_IT","og_type":"article","og_title":"Liquiritigenin Extract | Professional Liquiritigenin Manufacturer & Suppliers - Huatai Bio","og_description":"Buy certified Liquiritigenin extracts from active skincare ingredients manufacturer. Huatai Bio supplies COSMOS\/ISO\/HALAL certified Liquiritigenin for skincare formulations. Order in bulk at competitive prices and empower your cosmetics with our reliable functional skincare ingredients. Request samples and supplier quotes now.","og_url":"https:\/\/glabridinchina.com\/it\/prodotto\/liquiritigenin\/","og_site_name":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","article_modified_time":"2026-07-30T08:24:05+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/glabridinchina.com\/product\/liquiritigenin\/","url":"https:\/\/glabridinchina.com\/product\/liquiritigenin\/","name":"Liquiritigenin Powder Manufacturer & Suppliers - Huatai Bio","isPartOf":{"@id":"https:\/\/glabridinchina.com\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#primaryimage"},"image":{"@id":"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#primaryimage"},"thumbnailUrl":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg","datePublished":"2026-03-24T09:41:38+00:00","dateModified":"2026-07-30T08:24:05+00:00","description":"Cosmetic Grade Liquiritigenin from a premier active ingredients skincare manufacturer. Shaanxi Huatai Bio-fine Chemical offers ISO\/HALAL\/COSMOS certified Liquiritigenin for high-end formulations. Secure wholesale pricing and request free samples from a trusted global supplier today.","breadcrumb":{"@id":"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/glabridinchina.com\/product\/liquiritigenin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#primaryimage","url":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg","contentUrl":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2026\/03\/Liquiritigenin.jpg","width":800,"height":800,"caption":"Liquiritigenin"},{"@type":"BreadcrumbList","@id":"https:\/\/glabridinchina.com\/product\/liquiritigenin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/glabridinchina.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/glabridinchina.com\/products\/"},{"@type":"ListItem","position":3,"name":"Liquiritigenin"}]},{"@type":"WebSite","@id":"https:\/\/glabridinchina.com\/ru\/#website","url":"https:\/\/glabridinchina.com\/ru\/","name":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","description":"Huatai Bio-Fine Chemicals: ISO-certified manufacturer of high-purity skincare ingredients like Glabridin and Tranexamic Acid. Offering flexible supply with full documentation for brands &amp; OEMs worldwide.","publisher":{"@id":"https:\/\/glabridinchina.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glabridinchina.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/glabridinchina.com\/ru\/#organization","name":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","url":"https:\/\/glabridinchina.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp","contentUrl":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp","width":1278,"height":783,"caption":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd."},"image":{"@id":"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/product\/13042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/product\/13042\/revisions"}],"predecessor-version":[{"id":15491,"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/product\/13042\/revisions\/15491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/media\/13048"}],"wp:attachment":[{"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/media?parent=13042"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/etheme_brands?post=13042"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/product_cat?post=13042"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/glabridinchina.com\/it\/wp-json\/wp\/v2\/product_tag?post=13042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}