{"id":6797,"date":"2025-11-20T07:09:09","date_gmt":"2025-11-20T07:09:09","guid":{"rendered":"https:\/\/glabridinchina.com\/?p=6797"},"modified":"2025-11-20T07:09:44","modified_gmt":"2025-11-20T07:09:44","slug":"dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent","status":"publish","type":"post","link":"https:\/\/glabridinchina.com\/es\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/","title":{"rendered":"Glicirrizato dipot\u00e1sico: el agente antiinflamatorio de referencia."},"content":{"rendered":"<p><a href=\"https:\/\/glabridinchina.com\/es\/producto\/dipotassium-glycyrrhizate\/\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\">glicirrizato dipot\u00e1sico<\/mark><\/a> Antiinflamatorio se refiere a la acci\u00f3n calmante altamente efectiva de este compuesto, que es una sal derivada clave del \u00e1cido glicirr\u00edcico obtenido de forma natural de la ra\u00edz de regaliz. Como Ingrediente Activo Fundamental para el Cuidado de la Piel, el Dipotassium Glycyrrhizate es principalmente celebrado por su potente y r\u00e1pida eficacia antiinflamatoria, lo que lo convierte en un elemento b\u00e1sico en formulaciones dirigidas a pieles sensibles e irritaci\u00f3n. Su excelente naturaleza activa soluble en agua permite su inclusi\u00f3n f\u00e1cil y efectiva en pr\u00e1cticamente todas las matrices de cuidado de la piel a base de agua.<\/p><h2 class=\"wp-block-heading\" id=\"h-i-dipotassium-glycyrrhizate-the-anti-inflammatory-mechanism\">I. Dipotasio Glicirricinato: El Mecanismo Antiinflamatorio<\/h2><p>El efecto calmante superior del Dipotasio Glicirricinato se atribuye a su capacidad para modular las respuestas inflamatorias naturales del cuerpo, logrando a menudo resultados comparables a los corticosteroides pero sin los efectos secundarios asociados.<\/p><div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><a href=\"https:\/\/glabridinchina.com\/es\/producto\/dipotassium-glycyrrhizate\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-1024x768.jpg\" alt=\"glicirrizato dipot\u00e1sico\" class=\"wp-image-5568\" style=\"width:539px;height:auto\" srcset=\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-1024x768.jpg 1024w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-300x225.jpg 300w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-768x576.jpg 768w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-1536x1152.jpg 1536w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-2048x1536.jpg 2048w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-16x12.jpg 16w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-600x450.jpg 600w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-1x1.jpg 1w, https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11-10x8.jpg 10w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div><h3 class=\"wp-block-heading\" id=\"h-direct-modulation-of-inflammation\">Modulaci\u00f3n Directa de la Inflamaci\u00f3n<\/h3><ul class=\"wp-block-list\"><li>Metabolismo del Cortisol: El Dipotasio Glicirricinato act\u00faa inhibiendo la enzima beta-hidroxiesteroide deshidrogenasa. Esta inhibici\u00f3n ralentiza eficazmente la degradaci\u00f3n de los corticosteroides naturales (cortisol) en la piel, prolongando la respuesta antiinflamatoria inherente del cuerpo y proporcionando un calmante significativo para la piel.<\/li>\n\n<li>Reducci\u00f3n del Enrojecimiento: Este mecanismo es altamente efectivo para minimizar el enrojecimiento visible, la incomodidad y la hinchaz\u00f3n causados por factores estresantes ambientales externos, la exposici\u00f3n al sol o irritantes qu\u00edmicos, lo que lo convierte en el agente calmante perfecto para la mejor crema calmante.<\/li><\/ul><h3 class=\"wp-block-heading\" id=\"h-support-for-healing-and-recovery\">Apoyo a la Curaci\u00f3n y Recuperaci\u00f3n<\/h3><ul class=\"wp-block-list\"><li>Curaci\u00f3n Acelerada: Al suprimir r\u00e1pidamente la cascada inflamatoria, el Dipotasio Glicirricinato crea un entorno \u00f3ptimo para los mecanismos de reparaci\u00f3n natural de la piel, lo que conduce a una curaci\u00f3n m\u00e1s r\u00e1pida de da\u00f1os e irritaciones menores.<\/li><\/ul><h2 class=\"wp-block-heading\" id=\"h-ii-targeted-applications-sensitive-skin-serum-and-anti-acne-treatment\">II. Aplicaciones Dirigidas: S\u00e9rum para Piel Sensible y Tratamiento Anti-Acn\u00e9<\/h2><p>La seguridad y eficacia cl\u00ednica del Dipotasio Glicirricinato lo convierten en una materia prima cosm\u00e9tica preferida para aplicaciones dermatol\u00f3gicas y cosm\u00e9ticas especializadas.<\/p><h3 class=\"wp-block-heading\" id=\"h-ideal-for-sensitive-skin-serum\">Ideal para Suero para Piel Sensible<\/h3><ul class=\"wp-block-list\"><li>Eficacia Suave: Debido a su alta tolerancia establecida y su potente perfil antiinflamatorio, el Dipotasio Glicirricinato es una inclusi\u00f3n esencial en s\u00e9rums para piel sensible y productos para el cuidado del beb\u00e9, brindando beneficios terap\u00e9uticos sin sensibilizaci\u00f3n.<\/li><\/ul><h3 class=\"wp-block-heading\" id=\"h-support-for-anti-acne-treatment\">Soporte para el Tratamiento Anti-Acn\u00e9<\/h3><ul class=\"wp-block-list\"><li>Calma el Acn\u00e9: El Dipotasio Glicirricinato se utiliza ampliamente en <a class=\"wpil_keyword_link\" href=\"https:\/\/glabridinchina.com\/es\/product-category\/oil-control-anti-acne\/\" target=\"_blank\" rel=\"noopener\" title=\"antiacn\u00e9\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"4515\">antiacn\u00e9<\/a> formulaciones de tratamiento. Su acci\u00f3n antiinflamatoria reduce eficazmente la hinchaz\u00f3n y el enrojecimiento asociados con las lesiones de acn\u00e9, contribuyendo a una tez m\u00e1s calmada y clara. Act\u00faa sin\u00e9rgicamente con otros activos para reducir la irritaci\u00f3n general.<\/li><\/ul><h3 class=\"wp-block-heading\" id=\"h-skin-conditioning-benefits\">Beneficios para el acondicionamiento de la piel<\/h3><ul class=\"wp-block-list\"><li>Hidrataci\u00f3n y Sensaci\u00f3n: M\u00e1s all\u00e1 de su funci\u00f3n principal, el Dipotassium Glycyrrhizate tambi\u00e9n act\u00faa como un eficaz agente acondicionador de la piel, mejorando la sensaci\u00f3n y textura del producto final y contribuyendo al confort general de la piel.<\/li><\/ul><h2 class=\"wp-block-heading\" id=\"h-iii-commercial-sourcing-of-dipotassium-glycyrrhizate-powder\">III. Abastecimiento Comercial de Polvo de Dipotasio Glicirrizato<\/h2><p>Para los fabricantes, el valor comercial del Dipotasio Glicirrizato reside en su fiabilidad, estabilidad y facilidad de formulaci\u00f3n.<\/p><h3 class=\"wp-block-heading\" id=\"h-purity-and-formulation\">Pureza y Formulaci\u00f3n<\/h3><ul class=\"wp-block-list\"><li>Activo Hidrosoluble: Como Ingrediente Activo para el Cuidado de la Piel altamente soluble en agua, el Dipotasio Glicirrizato se suministra t\u00edpicamente en forma de polvo de alta pureza. Esta forma es excepcionalmente estable y f\u00e1cil de incorporar en s\u00e9rums, lociones y geles sin complejos obst\u00e1culos de formulaci\u00f3n.<\/li>\n\n<li>Eficacia Cl\u00ednica: El abastecimiento de una fuente fiable <a href=\"https:\/\/glabridinchina.com\/es\/producto\/dipotassium-glycyrrhizate\/\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\">Fabricante de Dipotasio Glicirrizato<\/mark><\/a> garantiza la pureza y estandarizaci\u00f3n necesarias para garantizar la eficacia cl\u00ednica antiinflamatoria esperada en el producto terminado.<\/li><\/ul><h3 class=\"wp-block-heading\" id=\"h-bulk-price-and-procurement\">Precios al por mayor y compras<\/h3><ul class=\"wp-block-list\"><li>Ventaja de Precio al por Mayor: Dado su uso ubicuo en el mercado del cuidado de la piel, asegurar un precio competitivo al por mayor para el polvo de Dipotasio Glicirrizato es fundamental para la gesti\u00f3n de costes en la producci\u00f3n cosm\u00e9tica a gran escala. La compra al por mayor a un Fabricante directo proporciona el mejor valor y un suministro constante.<\/li><\/ul><h2 class=\"wp-block-heading\" id=\"h-iv-conclusion\">IV. Conclusi\u00f3n<\/h2><p>El Dipotassium Glycyrrhizate es un Ingrediente Activo Vital para el Cuidado de la Piel, distinguido por su potente y bien comprendido mecanismo antiinflamatorio y su rendimiento superior como activo soluble en agua. Sigue siendo el agente calmante de referencia para sueros para piel sensible, tratamientos antiacn\u00e9 y las mejores cremas calmantes a nivel mundial.<\/p><hr class=\"wp-block-separator has-alpha-channel-opacity\" \/><p>Para compras al por mayor, cotizaciones o solicitudes de muestras:<\/p><p>Shaanxi Huatai Bio-fine Chemical Co., Ltd. es un Fabricante de Dipotasio Glicirrizato de alta calidad y un proveedor l\u00edder de polvo de Dipotasio Glicirrizato de alta pureza y otros ingredientes esenciales para el cuidado de la piel para las industrias cosm\u00e9tica y de cuidado personal a nivel mundial. Nuestras credenciales de calidad y seguridad incluyen: COSMOS, ISO 9001, ISO 22000, Certificaci\u00f3n HALAL e IQNET. Si est\u00e1 buscando comprar Dipotasio Glicirrizato al por mayor o requiere una cotizaci\u00f3n de precio al por mayor para este potente ingrediente funcional, por favor cont\u00e1ctenos directamente.<\/p><p>\ud83d\udd12 Obtenga su expediente t\u00e9cnico: acceda a la ficha t\u00e9cnica, la ficha de datos de seguridad del material, el certificado de an\u00e1lisis y los informes de eficacia cl\u00ednica.<\/p><p>\ud83d\udd2c Solicita una muestra gratuita: Prueba hoy mismo el poder estimulante del sistema inmunitario, estable y de alta eficacia del glicirrizato dipot\u00e1sico.<\/p><p>\ud83d\udcde Solicita un presupuesto personalizado: Hablamos sobre pedidos al por mayor y especificaciones de alta pureza.<\/p><p>Correo electr\u00f3nico: jelly@huataibio.com<\/p>","protected":false},"excerpt":{"rendered":"<p>El Dipotassium Glycyrrhizate Anti-inflammatory se refiere a la acci\u00f3n calmante altamente efectiva de este compuesto, que es una sal derivada clave del \u00e1cido glicirr\u00edcico obtenido de forma natural de\u2026<\/p>","protected":false},"author":8,"featured_media":5568,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-6797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.8 (Yoast SEO v24.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent - Shaanxi Huatai Bio-Fine Chemical Co., Ltd.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glabridinchina.com\/es\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent\" \/>\n<meta property=\"og:description\" content=\"Dipotassium Glycyrrhizate Anti-inflammatory refers to the highly effective calming action of this compound, which is a key salt derivative of glycyrrhizic acid naturally sourced from...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glabridinchina.com\/es\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/\" \/>\n<meta property=\"og:site_name\" content=\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-20T07:09:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T07:09:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"1772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Huatai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Huatai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/\"},\"author\":{\"name\":\"Huatai\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#\/schema\/person\/1fc9183390cde309170faf98dbabcaab\"},\"headline\":\"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent\",\"datePublished\":\"2025-11-20T07:09:09+00:00\",\"dateModified\":\"2025-11-20T07:09:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/\"},\"wordCount\":678,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/glabridinchina.com\/ru\/#organization\"},\"image\":{\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg\",\"articleSection\":[\"Product News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/\",\"url\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/\",\"name\":\"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent - Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\",\"isPartOf\":{\"@id\":\"https:\/\/glabridinchina.com\/ru\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg\",\"datePublished\":\"2025-11-20T07:09:09+00:00\",\"dateModified\":\"2025-11-20T07:09:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage\",\"url\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg\",\"contentUrl\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg\",\"width\":2362,\"height\":1772,\"caption\":\"Dipotassium Glycyrrhizate\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/glabridinchina.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#website\",\"url\":\"https:\/\/glabridinchina.com\/ru\/\",\"name\":\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\",\"description\":\"Huatai Bio-Fine Chemicals: ISO-certified manufacturer of high-purity skincare ingredients like Glabridin and Tranexamic Acid. Offering flexible supply with full documentation for brands &amp; OEMs worldwide.\",\"publisher\":{\"@id\":\"https:\/\/glabridinchina.com\/ru\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/glabridinchina.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#organization\",\"name\":\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\",\"url\":\"https:\/\/glabridinchina.com\/ru\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp\",\"contentUrl\":\"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp\",\"width\":1278,\"height\":783,\"caption\":\"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.\"},\"image\":{\"@id\":\"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/glabridinchina.com\/ru\/#\/schema\/person\/1fc9183390cde309170faf98dbabcaab\",\"name\":\"Huatai\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent - Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glabridinchina.com\/es\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/","og_locale":"es_ES","og_type":"article","og_title":"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent","og_description":"Dipotassium Glycyrrhizate Anti-inflammatory refers to the highly effective calming action of this compound, which is a key salt derivative of glycyrrhizic acid naturally sourced from...","og_url":"https:\/\/glabridinchina.com\/es\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/","og_site_name":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","article_published_time":"2025-11-20T07:09:09+00:00","article_modified_time":"2025-11-20T07:09:44+00:00","og_image":[{"width":2362,"height":1772,"url":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg","type":"image\/jpeg"}],"author":"Huatai","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Huatai","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#article","isPartOf":{"@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/"},"author":{"name":"Huatai","@id":"https:\/\/glabridinchina.com\/ru\/#\/schema\/person\/1fc9183390cde309170faf98dbabcaab"},"headline":"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent","datePublished":"2025-11-20T07:09:09+00:00","dateModified":"2025-11-20T07:09:44+00:00","mainEntityOfPage":{"@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/"},"wordCount":678,"commentCount":0,"publisher":{"@id":"https:\/\/glabridinchina.com\/ru\/#organization"},"image":{"@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage"},"thumbnailUrl":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg","articleSection":["Product News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/","url":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/","name":"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent - Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","isPartOf":{"@id":"https:\/\/glabridinchina.com\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage"},"image":{"@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage"},"thumbnailUrl":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg","datePublished":"2025-11-20T07:09:09+00:00","dateModified":"2025-11-20T07:09:44+00:00","breadcrumb":{"@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#primaryimage","url":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg","contentUrl":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2025\/10\/11.jpg","width":2362,"height":1772,"caption":"Dipotassium Glycyrrhizate"},{"@type":"BreadcrumbList","@id":"https:\/\/glabridinchina.com\/dipotassium-glycyrrhizate-the-benchmark-anti-inflammatory-agent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/glabridinchina.com\/"},{"@type":"ListItem","position":2,"name":"Dipotassium Glycyrrhizate: The Benchmark Anti-inflammatory Agent"}]},{"@type":"WebSite","@id":"https:\/\/glabridinchina.com\/ru\/#website","url":"https:\/\/glabridinchina.com\/ru\/","name":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","description":"Huatai Bio-Fine Chemicals: ISO-certified manufacturer of high-purity skincare ingredients like Glabridin and Tranexamic Acid. Offering flexible supply with full documentation for brands &amp; OEMs worldwide.","publisher":{"@id":"https:\/\/glabridinchina.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glabridinchina.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/glabridinchina.com\/ru\/#organization","name":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd.","url":"https:\/\/glabridinchina.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp","contentUrl":"https:\/\/glabridinchina.com\/wp-content\/uploads\/2024\/10\/\u516c\u53f8LOGO.webp","width":1278,"height":783,"caption":"Shaanxi Huatai Bio-Fine Chemical Co., Ltd."},"image":{"@id":"https:\/\/glabridinchina.com\/ru\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/glabridinchina.com\/ru\/#\/schema\/person\/1fc9183390cde309170faf98dbabcaab","name":"Huatai"}]}},"_links":{"self":[{"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/posts\/6797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/comments?post=6797"}],"version-history":[{"count":0,"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/posts\/6797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/media\/5568"}],"wp:attachment":[{"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/media?parent=6797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/categories?post=6797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/glabridinchina.com\/es\/wp-json\/wp\/v2\/tags?post=6797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}